{"id":50,"count":12,"description":"M20 - Nietenpressen","link":"https:\/\/www.steinfels-kg.de\/en\/sell\/fastener\/rivet-headers\/","name":"Rivet headers","slug":"nietenpressen","taxonomy":"category","parent":47,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Rivet headers - 2nd-hand - for sale - HSH Steinfels<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.steinfels-kg.de\/verkauf\/schrauben\/nietenpressen\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rivet headers - 2nd-hand - for sale - HSH Steinfels\" \/>\n<meta property=\"og:description\" content=\"M20 &#8211; Nietenpressen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.steinfels-kg.de\/verkauf\/schrauben\/nietenpressen\/\" \/>\n<meta property=\"og:site_name\" content=\"HSH Steinfels\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\n\t    \"@context\": \"https:\/\/schema.org\",\n\t    \"@graph\": [\n\t        {\n\t            \"@type\": \"CollectionPage\",\n\t            \"@id\": \"https:\/\/www.steinfels-kg.de\/verkauf\/schrauben\/nietenpressen\/\",\n\t            \"url\": \"https:\/\/www.steinfels-kg.de\/verkauf\/schrauben\/nietenpressen\/\",\n\t            \"name\": \"Rivet headers - 2nd-hand - for sale - HSH Steinfels\",\n\t            \"isPartOf\": {\n\t                \"@id\": \"https:\/\/www.steinfels-kg.de\/tr\/#website\"\n\t            },\n\t            \"breadcrumb\": {\n\t                \"@id\": \"https:\/\/www.steinfels-kg.de\/verkauf\/schrauben\/nietenpressen\/#breadcrumb\"\n\t            },\n\t            \"inLanguage\": \"en-GB\"\n\t        },\n\t        {\n\t            \"@type\": \"BreadcrumbList\",\n\t            \"@id\": \"https:\/\/www.steinfels-kg.de\/verkauf\/schrauben\/nietenpressen\/#breadcrumb\",\n\t            \"itemListElement\": [\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 1,\n\t                    \"name\": \"Home\",\n\t                    \"item\": \"https:\/\/www.steinfels-kg.de\/\"\n\t                },\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 2,\n\t                    \"name\": \"Vida end\u00fcstrisi\",\n\t                    \"item\": \"https:\/\/www.steinfels-kg.de\/tr\/selling-tr\/baglanti-elemanlari\/\"\n\t                },\n\t                {\n\t                    \"@type\": \"ListItem\",\n\t                    \"position\": 3,\n\t                    \"name\": \"Nietenpressen\"\n\t                }\n\t            ]\n\t        },\n\t        {\n\t            \"@type\": \"WebSite\",\n\t            \"@id\": \"https:\/\/www.steinfels-kg.de\/tr\/#website\",\n\t            \"url\": \"https:\/\/www.steinfels-kg.de\/tr\/\",\n\t            \"name\": \"HSH Steinfels\",\n\t            \"description\": \"H\u00e4ndler f\u00fcr gebrauchte Maschinen\",\n\t            \"publisher\": {\n\t                \"@id\": \"https:\/\/www.steinfels-kg.de\/tr\/#organization\"\n\t            },\n\t            \"potentialAction\": [\n\t                {\n\t                    \"@type\": \"SearchAction\",\n\t                    \"target\": {\n\t                        \"@type\": \"EntryPoint\",\n\t                        \"urlTemplate\": \"https:\/\/www.steinfels-kg.de\/tr\/?s={search_term_string}\"\n\t                    },\n\t                    \"query-input\": {\n\t                        \"@type\": \"PropertyValueSpecification\",\n\t                        \"valueRequired\": true,\n\t                        \"valueName\": \"search_term_string\"\n\t                    }\n\t                }\n\t            ],\n\t            \"inLanguage\": \"en-GB\"\n\t        },\n\t        {\n\t            \"@type\": \"Organization\",\n\t            \"@id\": \"https:\/\/www.steinfels-kg.de\/tr\/#organization\",\n\t            \"name\": \"HSH Steinfels\",\n\t            \"url\": \"https:\/\/www.steinfels-kg.de\/tr\/\",\n\t            \"logo\": {\n\t                \"@type\": \"ImageObject\",\n\t                \"inLanguage\": \"en-GB\",\n\t                \"@id\": \"https:\/\/www.steinfels-kg.de\/tr\/#\/schema\/logo\/image\/\",\n\t                \"url\": \"https:\/\/www.steinfels-kg.de\/wp-content\/uploads\/favicon-ng.png\",\n\t                \"contentUrl\": \"https:\/\/www.steinfels-kg.de\/wp-content\/uploads\/favicon-ng.png\",\n\t                \"width\": 500,\n\t                \"height\": 500,\n\t                \"caption\": \"HSH Steinfels\"\n\t            },\n\t            \"image\": {\n\t                \"@id\": \"https:\/\/www.steinfels-kg.de\/tr\/#\/schema\/logo\/image\/\"\n\t            },\n\t            \"sameAs\": [\n\t                \"https:\/\/www.facebook.com\/HelmutSteinfels\"\n\t            ]\n\t        }\n\t    ]\n\t}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rivet headers - 2nd-hand - for sale - HSH Steinfels","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.steinfels-kg.de\/verkauf\/schrauben\/nietenpressen\/","og_locale":"en_GB","og_type":"article","og_title":"Rivet headers - 2nd-hand - for sale - HSH Steinfels","og_description":"M20 &#8211; Nietenpressen","og_url":"https:\/\/www.steinfels-kg.de\/verkauf\/schrauben\/nietenpressen\/","og_site_name":"HSH Steinfels","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.steinfels-kg.de\/verkauf\/schrauben\/nietenpressen\/","url":"https:\/\/www.steinfels-kg.de\/verkauf\/schrauben\/nietenpressen\/","name":"Rivet headers - 2nd-hand - for sale - HSH Steinfels","isPartOf":{"@id":"https:\/\/www.steinfels-kg.de\/tr\/#website"},"breadcrumb":{"@id":"https:\/\/www.steinfels-kg.de\/verkauf\/schrauben\/nietenpressen\/#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/www.steinfels-kg.de\/verkauf\/schrauben\/nietenpressen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.steinfels-kg.de\/"},{"@type":"ListItem","position":2,"name":"Vida end\u00fcstrisi","item":"https:\/\/www.steinfels-kg.de\/tr\/selling-tr\/baglanti-elemanlari\/"},{"@type":"ListItem","position":3,"name":"Nietenpressen"}]},{"@type":"WebSite","@id":"https:\/\/www.steinfels-kg.de\/tr\/#website","url":"https:\/\/www.steinfels-kg.de\/tr\/","name":"HSH Steinfels","description":"H\u00e4ndler f\u00fcr gebrauchte Maschinen","publisher":{"@id":"https:\/\/www.steinfels-kg.de\/tr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.steinfels-kg.de\/tr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.steinfels-kg.de\/tr\/#organization","name":"HSH Steinfels","url":"https:\/\/www.steinfels-kg.de\/tr\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.steinfels-kg.de\/tr\/#\/schema\/logo\/image\/","url":"https:\/\/www.steinfels-kg.de\/wp-content\/uploads\/favicon-ng.png","contentUrl":"https:\/\/www.steinfels-kg.de\/wp-content\/uploads\/favicon-ng.png","width":500,"height":500,"caption":"HSH Steinfels"},"image":{"@id":"https:\/\/www.steinfels-kg.de\/tr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/HelmutSteinfels"]}]}},"_links":{"self":[{"href":"https:\/\/www.steinfels-kg.de\/en\/wp-json\/wp\/v2\/categories\/50","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.steinfels-kg.de\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.steinfels-kg.de\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/www.steinfels-kg.de\/en\/wp-json\/wp\/v2\/categories\/47"}],"wp:post_type":[{"href":"https:\/\/www.steinfels-kg.de\/en\/wp-json\/wp\/v2\/posts?categories=50"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}